{"id":2981,"date":"2024-07-24T09:20:44","date_gmt":"2024-07-24T09:20:44","guid":{"rendered":"https:\/\/www.deudafix.es\/blog\/?post_type=ufaq&#038;p=2981"},"modified":"2024-07-24T09:55:57","modified_gmt":"2024-07-24T09:55:57","slug":"que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta","status":"publish","type":"ufaq","link":"https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/","title":{"rendered":"\u00bfQu\u00e9 pasa si un cliente que se encuentra en estado demanda repartida nos dice que le han bloqueado la cuenta?"},"content":{"rendered":"<style>.ewd-ufaq-post-margin-symbol { background-color: #77a105 !important; }.ewd-ufaq-post-margin-symbol { color: #fbfbfb !important; }.ewd-ufaq-faq-display-style-block.ewd-ufaq-post-active, .ewd-ufaq-faq-display-style-block.ewd-ufaq-post-active a,.ewd-ufaq-faq-display-style-block:hover, .ewd-ufaq-faq-display-style-block:hover a, .ewd-ufaq-faq-display-style-block:hover h4 { background-color: #222d65 !important; }.ewd-ufaq-faq-display-style-border_block.ewd-ufaq-post-active, .ewd-ufaq-faq-display-style-border_block:hover, .ewd-ufaq-faq-display-style-border_block:hover h4 { background-color: #222d65 !important; }.ewd-ufaq-faq-display-style-border_block .ewd-ufaq-faq-body { border-color: #222d65 !important; }.ewd-ufaq-faq-display-style-border_block .comment-reply-title, .ewd-ufaq-faq-display-style-border_block:hover .comment-reply-title { background-color: transparent !important; }.ewd-ufaq-faq-div {\r\n    margin: 7px 0 !important;\r\n    padding: 2px 7px !important;\r\n    clear: both;\r\n    border-width: 1px;\r\n    border: 1px #42A5F5 !important;\r\n    box-sizing: border-box !important;\r\n    \/* border-style: solid !important; *\/\r\n}<\/style><div  class=\"ewd-ufaq-faq-list ewd-ufaq-page-type-distinct\" id='ewd-ufaq-faq-list'>\r\n\r\n\t<input type='hidden' name='include_category' value='' id='ewd-ufaq-include-category' \/>\r\n<input type='hidden' name='exclude_category' value='' id='ewd-ufaq-exclude-category' \/>\r\n<input type='hidden' name='orderby' value='title' id='ewd-ufaq-orderby' \/>\r\n<input type='hidden' name='order' value='asc' id='ewd-ufaq-order' \/>\r\n<input type='hidden' name='post_count' value='-1' id='ewd-ufaq-post-count' \/>\r\n<input type='hidden' name='current_url' value='\/blog\/wp-json\/wp\/v2\/ufaq\/2981' id='ewd-ufaq-current-url' \/>\r\n\t\r\n\t\r\n\t<div class='ewd-ufaq-faqs'>\r\n\r\n\t\t<div  class=\"ewd-ufaq-faq-div ewd-ufaq-faq-column-count-one ewd-ufaq-faq-responsive-columns- ewd-ufaq-faq-display-style-contemporary ewd-ufaq-can-be-toggled\" id='ewd-ufaq-post-2981-iwjFTEEuB4' data-post_id='2981'>\r\n\r\n\t<div class='ewd-ufaq-faq-title ewd-ufaq-faq-toggle'>\r\n\t\r\n\t<a class='ewd-ufaq-post-margin'  href='https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/'>\r\n\r\n\t\t<div class='ewd-ufaq-post-margin-symbol ewd-ufaq-'>\r\n\t\t\t<span >A<\/span>\r\n\t\t<\/div>\r\n\r\n\t\t<div class='ewd-ufaq-faq-title-text'>\r\n\r\n\t\t\t<h4 id=\"boomdevs_1\">\r\n\t\t\t\t\u00bfQu\u00e9 pasa si un cliente que se encuentra en estado demanda repartida nos dice que le han bloqueado la cuenta?\t\t\t<\/h4>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t<div class='ewd-ufaq-clear'><\/div>\r\n\r\n\t<\/a>\r\n\t\r\n<\/div>\r\n\t\r\n\t<div class='ewd-ufaq-faq-body ' >\r\n\r\n\t\t\r\n\t\t\t<div class='ewd-ufaq-faq-categories'>\r\n\t\r\n\tCategory:\r\n\t\r\n\t\tAtenci\u00f3n al cliente\r\n\t\r\n<\/div>\r\n\t\t\r\n\t\t\t<div class='ewd-ufaq-post-margin ewd-ufaq-faq-post'>\r\n\t<p>Pueden ser varias opciones:<\/p>\n<ul>\n<li>La m\u00e1s frecuente es que por impago de alguna comisi\u00f3n o por operativa interna de la entidad bancaria hayan bloqueado la tarjeta, que no la cuenta. Esto supone que el cliente puede operar sin problema desde su cuenta y nosotros no tenemos que intervenir para nada<\/li>\n<li>Es posible que s\u00ed que le hayan bloqueado la cuenta pero, por alg\u00fan error del Procurador o del Juzgado, no nos hayan notificado el Auto de Concurso. En este caso habr\u00eda que revisar el BOE y RPC para verificar si estuviera publicado y ya nos pondr\u00edamos en contacto con la entidad bancaria<\/li>\n<\/ul>\n<\/div>\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t<\/div>\r\n\r\n<\/div>\r\n\t<\/div>\r\n\r\n\t\r\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A \u00bfQu\u00e9 pasa si un cliente que se encuentra en estado demanda repartida nos dice que le han bloqueado la cuenta? Category: Atenci\u00f3n al cliente Pueden ser varias opciones: La m\u00e1s frecuente es que por impago de alguna comisi\u00f3n o por operativa interna de la entidad bancaria hayan bloqueado la tarjeta, que no la cuenta. [&hellip;]<\/p>\n","protected":false},"author":3,"comment_status":"open","ping_status":"closed","template":"","ufaq-category":[29],"ufaq-tag":[],"class_list":["post-2981","ufaq","type-ufaq","status-publish","hentry","ufaq-category-atencion-al-cliente","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 pasa si un cliente que se encuentra en estado demanda repartida nos dice que le han bloqueado la cuenta? - Deudafix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 pasa si un cliente que se encuentra en estado demanda repartida nos dice que le han bloqueado la cuenta? - Deudafix\" \/>\n<meta property=\"og:description\" content=\"A \u00bfQu\u00e9 pasa si un cliente que se encuentra en estado demanda repartida nos dice que le han bloqueado la cuenta? Category: Atenci\u00f3n al cliente Pueden ser varias opciones: La m\u00e1s frecuente es que por impago de alguna comisi\u00f3n o por operativa interna de la entidad bancaria hayan bloqueado la tarjeta, que no la cuenta. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/\" \/>\n<meta property=\"og:site_name\" content=\"Deudafix\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-24T09:55:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/\",\"url\":\"https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/\",\"name\":\"\u00bfQu\u00e9 pasa si un cliente que se encuentra en estado demanda repartida nos dice que le han bloqueado la cuenta? - Deudafix\",\"isPartOf\":{\"@id\":\"https:\/\/www.deudafix.es\/blog\/#website\"},\"datePublished\":\"2024-07-24T09:20:44+00:00\",\"dateModified\":\"2024-07-24T09:55:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.deudafix.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQs\",\"item\":\"https:\/\/www.deudafix.es\/blog\/ufaq\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfQu\u00e9 pasa si un cliente que se encuentra en estado demanda repartida nos dice que le han bloqueado la cuenta?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.deudafix.es\/blog\/#website\",\"url\":\"https:\/\/www.deudafix.es\/blog\/\",\"name\":\"Deudafix\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.deudafix.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.deudafix.es\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.deudafix.es\/blog\/#organization\",\"name\":\"Deudafix Reparadora Legal Group SL\",\"url\":\"https:\/\/www.deudafix.es\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.deudafix.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.deudafix.es\/blog\/wp-content\/uploads\/2021\/05\/PNGArtboard-1-1.png\",\"contentUrl\":\"https:\/\/www.deudafix.es\/blog\/wp-content\/uploads\/2021\/05\/PNGArtboard-1-1.png\",\"width\":1248,\"height\":326,\"caption\":\"Deudafix Reparadora Legal Group SL\"},\"image\":{\"@id\":\"https:\/\/www.deudafix.es\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 pasa si un cliente que se encuentra en estado demanda repartida nos dice que le han bloqueado la cuenta? - Deudafix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfQu\u00e9 pasa si un cliente que se encuentra en estado demanda repartida nos dice que le han bloqueado la cuenta? - Deudafix","og_description":"A \u00bfQu\u00e9 pasa si un cliente que se encuentra en estado demanda repartida nos dice que le han bloqueado la cuenta? Category: Atenci\u00f3n al cliente Pueden ser varias opciones: La m\u00e1s frecuente es que por impago de alguna comisi\u00f3n o por operativa interna de la entidad bancaria hayan bloqueado la tarjeta, que no la cuenta. [&hellip;]","og_url":"https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/","og_site_name":"Deudafix","article_modified_time":"2024-07-24T09:55:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/","url":"https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/","name":"\u00bfQu\u00e9 pasa si un cliente que se encuentra en estado demanda repartida nos dice que le han bloqueado la cuenta? - Deudafix","isPartOf":{"@id":"https:\/\/www.deudafix.es\/blog\/#website"},"datePublished":"2024-07-24T09:20:44+00:00","dateModified":"2024-07-24T09:55:57+00:00","breadcrumb":{"@id":"https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.deudafix.es\/blog\/ufaq\/que-pasa-si-un-cliente-que-se-encuentra-en-estado-demanda-repartida-nos-dice-que-le-han-bloqueado-la-cuenta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.deudafix.es\/blog\/"},{"@type":"ListItem","position":2,"name":"FAQs","item":"https:\/\/www.deudafix.es\/blog\/ufaq\/"},{"@type":"ListItem","position":3,"name":"\u00bfQu\u00e9 pasa si un cliente que se encuentra en estado demanda repartida nos dice que le han bloqueado la cuenta?"}]},{"@type":"WebSite","@id":"https:\/\/www.deudafix.es\/blog\/#website","url":"https:\/\/www.deudafix.es\/blog\/","name":"Deudafix","description":"","publisher":{"@id":"https:\/\/www.deudafix.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deudafix.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.deudafix.es\/blog\/#organization","name":"Deudafix Reparadora Legal Group SL","url":"https:\/\/www.deudafix.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.deudafix.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deudafix.es\/blog\/wp-content\/uploads\/2021\/05\/PNGArtboard-1-1.png","contentUrl":"https:\/\/www.deudafix.es\/blog\/wp-content\/uploads\/2021\/05\/PNGArtboard-1-1.png","width":1248,"height":326,"caption":"Deudafix Reparadora Legal Group SL"},"image":{"@id":"https:\/\/www.deudafix.es\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/ufaq\/2981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/ufaq"}],"about":[{"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/types\/ufaq"}],"author":[{"embeddable":true,"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/comments?post=2981"}],"wp:attachment":[{"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/media?parent=2981"}],"wp:term":[{"taxonomy":"ufaq-category","embeddable":true,"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/ufaq-category?post=2981"},{"taxonomy":"ufaq-tag","embeddable":true,"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/ufaq-tag?post=2981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}