{"id":1464,"date":"2022-02-14T09:27:45","date_gmt":"2022-02-14T09:27:45","guid":{"rendered":"https:\/\/www.deudafix.es\/blog\/?post_type=ufaq&#038;p=1464"},"modified":"2022-08-16T13:38:51","modified_gmt":"2022-08-16T13:38:51","slug":"cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley","status":"publish","type":"ufaq","link":"https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/","title":{"rendered":"\u00bfCu\u00e1les son los delitos que no deben haberse cometido en los \u00faltimos 10 a\u00f1os para poder acogerse a esta Ley?"},"content":{"rendered":"<style>.ewd-ufaq-post-margin-symbol { background-color: #77a105 !important; }.ewd-ufaq-post-margin-symbol { color: #fbfbfb !important; }.ewd-ufaq-faq-display-style-block.ewd-ufaq-post-active, .ewd-ufaq-faq-display-style-block.ewd-ufaq-post-active a,.ewd-ufaq-faq-display-style-block:hover, .ewd-ufaq-faq-display-style-block:hover a, .ewd-ufaq-faq-display-style-block:hover h4 { background-color: #222d65 !important; }.ewd-ufaq-faq-display-style-border_block.ewd-ufaq-post-active, .ewd-ufaq-faq-display-style-border_block:hover, .ewd-ufaq-faq-display-style-border_block:hover h4 { background-color: #222d65 !important; }.ewd-ufaq-faq-display-style-border_block .ewd-ufaq-faq-body { border-color: #222d65 !important; }.ewd-ufaq-faq-display-style-border_block .comment-reply-title, .ewd-ufaq-faq-display-style-border_block:hover .comment-reply-title { background-color: transparent !important; }.ewd-ufaq-faq-div {\r\n    margin: 7px 0 !important;\r\n    padding: 2px 7px !important;\r\n    clear: both;\r\n    border-width: 1px;\r\n    border: 1px #42A5F5 !important;\r\n    box-sizing: border-box !important;\r\n    \/* border-style: solid !important; *\/\r\n}<\/style><div  class=\"ewd-ufaq-faq-list ewd-ufaq-page-type-distinct\" id='ewd-ufaq-faq-list'>\r\n\r\n\t<input type='hidden' name='include_category' value='' id='ewd-ufaq-include-category' \/>\r\n<input type='hidden' name='exclude_category' value='' id='ewd-ufaq-exclude-category' \/>\r\n<input type='hidden' name='orderby' value='title' id='ewd-ufaq-orderby' \/>\r\n<input type='hidden' name='order' value='asc' id='ewd-ufaq-order' \/>\r\n<input type='hidden' name='post_count' value='-1' id='ewd-ufaq-post-count' \/>\r\n<input type='hidden' name='current_url' value='\/blog\/wp-json\/wp\/v2\/ufaq\/1464' id='ewd-ufaq-current-url' \/>\r\n\t\r\n\t\r\n\t<div class='ewd-ufaq-faqs'>\r\n\r\n\t\t<div  class=\"ewd-ufaq-faq-div ewd-ufaq-faq-column-count-one ewd-ufaq-faq-responsive-columns- ewd-ufaq-faq-display-style-contemporary ewd-ufaq-can-be-toggled\" id='ewd-ufaq-post-1464-84isC4L7Kj' data-post_id='1464'>\r\n\r\n\t<div class='ewd-ufaq-faq-title ewd-ufaq-faq-toggle'>\r\n\t\r\n\t<a class='ewd-ufaq-post-margin'  href='https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/'>\r\n\r\n\t\t<div class='ewd-ufaq-post-margin-symbol ewd-ufaq-'>\r\n\t\t\t<span >A<\/span>\r\n\t\t<\/div>\r\n\r\n\t\t<div class='ewd-ufaq-faq-title-text'>\r\n\r\n\t\t\t<h4 id=\"boomdevs_1\">\r\n\t\t\t\t\u00bfCu\u00e1les son los delitos que no deben haberse cometido en los \u00faltimos 10 a\u00f1os para poder acogerse a esta Ley?\t\t\t<\/h4>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t<div class='ewd-ufaq-clear'><\/div>\r\n\r\n\t<\/a>\r\n\t\r\n<\/div>\r\n\t\r\n\t<div class='ewd-ufaq-faq-body ' >\r\n\r\n\t\t\r\n\t\t\t<div class='ewd-ufaq-faq-categories'>\r\n\t\r\n\tCategory:\r\n\t\r\n\t\tInformaci\u00f3n general\r\n\t\r\n<\/div>\r\n\t\t\r\n\t\t\t<div class='ewd-ufaq-post-margin ewd-ufaq-faq-post'>\r\n\t<p><span style=\"font-weight: 400;\">No deben existir antecedentes penales por delitos contra el patrimonio, contra el orden socioecon\u00f3mico, falsedad documental, contra la Hacienda P\u00fablica y la Seguridad Social o contra los derechos de los trabajadores en los \u00faltimos 10 a\u00f1os anteriores a la declaraci\u00f3n del concurso.<\/span><\/p>\n<p>Excepci\u00f3n: <span style=\"font-weight: 400;\">Si en la fecha de presentaci\u00f3n de la solicitud de exoneraci\u00f3n se hubieran cancelado los antecedentes penales, el cliente si cumplir\u00e1 con los requisitos para acogerse a la LSO.<\/span><\/p>\n<\/div>\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t\t\t\r\n\t\t\r\n\t<\/div>\r\n\r\n<\/div>\r\n\t<\/div>\r\n\r\n\t\r\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A \u00bfCu\u00e1les son los delitos que no deben haberse cometido en los \u00faltimos 10 a\u00f1os para poder acogerse a esta Ley? Category: Informaci\u00f3n general No deben existir antecedentes penales por delitos contra el patrimonio, contra el orden socioecon\u00f3mico, falsedad documental, contra la Hacienda P\u00fablica y la Seguridad Social o contra los derechos de los trabajadores [&hellip;]<\/p>\n","protected":false},"author":3,"comment_status":"open","ping_status":"closed","template":"","ufaq-category":[27],"ufaq-tag":[],"class_list":["post-1464","ufaq","type-ufaq","status-publish","hentry","ufaq-category-informacion-general","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfCu\u00e1les son los delitos que no deben haberse cometido en los \u00faltimos 10 a\u00f1os para poder acogerse a esta Ley? - Deudafix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1les son los delitos que no deben haberse cometido en los \u00faltimos 10 a\u00f1os para poder acogerse a esta Ley? - Deudafix\" \/>\n<meta property=\"og:description\" content=\"A \u00bfCu\u00e1les son los delitos que no deben haberse cometido en los \u00faltimos 10 a\u00f1os para poder acogerse a esta Ley? Category: Informaci\u00f3n general No deben existir antecedentes penales por delitos contra el patrimonio, contra el orden socioecon\u00f3mico, falsedad documental, contra la Hacienda P\u00fablica y la Seguridad Social o contra los derechos de los trabajadores [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/\" \/>\n<meta property=\"og:site_name\" content=\"Deudafix\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-16T13:38:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/\",\"url\":\"https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/\",\"name\":\"\u00bfCu\u00e1les son los delitos que no deben haberse cometido en los \u00faltimos 10 a\u00f1os para poder acogerse a esta Ley? - Deudafix\",\"isPartOf\":{\"@id\":\"https:\/\/www.deudafix.es\/blog\/#website\"},\"datePublished\":\"2022-02-14T09:27:45+00:00\",\"dateModified\":\"2022-08-16T13:38:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.deudafix.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQs\",\"item\":\"https:\/\/www.deudafix.es\/blog\/ufaq\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfCu\u00e1les son los delitos que no deben haberse cometido en los \u00faltimos 10 a\u00f1os para poder acogerse a esta Ley?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.deudafix.es\/blog\/#website\",\"url\":\"https:\/\/www.deudafix.es\/blog\/\",\"name\":\"Deudafix\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.deudafix.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.deudafix.es\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.deudafix.es\/blog\/#organization\",\"name\":\"Deudafix Reparadora Legal Group SL\",\"url\":\"https:\/\/www.deudafix.es\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.deudafix.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.deudafix.es\/blog\/wp-content\/uploads\/2021\/05\/PNGArtboard-1-1.png\",\"contentUrl\":\"https:\/\/www.deudafix.es\/blog\/wp-content\/uploads\/2021\/05\/PNGArtboard-1-1.png\",\"width\":1248,\"height\":326,\"caption\":\"Deudafix Reparadora Legal Group SL\"},\"image\":{\"@id\":\"https:\/\/www.deudafix.es\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1les son los delitos que no deben haberse cometido en los \u00faltimos 10 a\u00f1os para poder acogerse a esta Ley? - Deudafix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfCu\u00e1les son los delitos que no deben haberse cometido en los \u00faltimos 10 a\u00f1os para poder acogerse a esta Ley? - Deudafix","og_description":"A \u00bfCu\u00e1les son los delitos que no deben haberse cometido en los \u00faltimos 10 a\u00f1os para poder acogerse a esta Ley? Category: Informaci\u00f3n general No deben existir antecedentes penales por delitos contra el patrimonio, contra el orden socioecon\u00f3mico, falsedad documental, contra la Hacienda P\u00fablica y la Seguridad Social o contra los derechos de los trabajadores [&hellip;]","og_url":"https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/","og_site_name":"Deudafix","article_modified_time":"2022-08-16T13:38:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/","url":"https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/","name":"\u00bfCu\u00e1les son los delitos que no deben haberse cometido en los \u00faltimos 10 a\u00f1os para poder acogerse a esta Ley? - Deudafix","isPartOf":{"@id":"https:\/\/www.deudafix.es\/blog\/#website"},"datePublished":"2022-02-14T09:27:45+00:00","dateModified":"2022-08-16T13:38:51+00:00","breadcrumb":{"@id":"https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.deudafix.es\/blog\/ufaq\/cuales-son-los-delitos-que-no-deben-haberse-cometido-en-los-ultimos-10-anos-para-poder-acogerse-a-esta-ley\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.deudafix.es\/blog\/"},{"@type":"ListItem","position":2,"name":"FAQs","item":"https:\/\/www.deudafix.es\/blog\/ufaq\/"},{"@type":"ListItem","position":3,"name":"\u00bfCu\u00e1les son los delitos que no deben haberse cometido en los \u00faltimos 10 a\u00f1os para poder acogerse a esta Ley?"}]},{"@type":"WebSite","@id":"https:\/\/www.deudafix.es\/blog\/#website","url":"https:\/\/www.deudafix.es\/blog\/","name":"Deudafix","description":"","publisher":{"@id":"https:\/\/www.deudafix.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deudafix.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.deudafix.es\/blog\/#organization","name":"Deudafix Reparadora Legal Group SL","url":"https:\/\/www.deudafix.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.deudafix.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deudafix.es\/blog\/wp-content\/uploads\/2021\/05\/PNGArtboard-1-1.png","contentUrl":"https:\/\/www.deudafix.es\/blog\/wp-content\/uploads\/2021\/05\/PNGArtboard-1-1.png","width":1248,"height":326,"caption":"Deudafix Reparadora Legal Group SL"},"image":{"@id":"https:\/\/www.deudafix.es\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/ufaq\/1464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/ufaq"}],"about":[{"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/types\/ufaq"}],"author":[{"embeddable":true,"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/comments?post=1464"}],"wp:attachment":[{"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/media?parent=1464"}],"wp:term":[{"taxonomy":"ufaq-category","embeddable":true,"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/ufaq-category?post=1464"},{"taxonomy":"ufaq-tag","embeddable":true,"href":"https:\/\/www.deudafix.es\/blog\/wp-json\/wp\/v2\/ufaq-tag?post=1464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}